{"id":123091,"date":"2026-05-28T11:58:54","date_gmt":"2026-05-28T16:58:54","guid":{"rendered":"https:\/\/www.essensedesigns.com\/?post_type=trunk-show&#038;p=123091"},"modified":"2026-05-28T11:58:54","modified_gmt":"2026-05-28T16:58:54","slug":"trunk-show-7590","status":"publish","type":"trunk-show","link":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/","title":{"rendered":"Trunk Show"},"author":10,"menu_order":0,"template":"","class_list":["post-123091","trunk-show","type-trunk-show","status-publish","hentry","location-brand-essense"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trunk Show - Essense of Australia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trunk Show\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/\" \/>\n<meta property=\"og:site_name\" content=\"Essense of Australia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/essenseofaustralia\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/09\/social-share-logo-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/\",\"url\":\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/\",\"name\":\"Trunk Show - Essense of Australia\",\"isPartOf\":{\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#website\"},\"datePublished\":\"2026-05-28T16:58:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.essensedesigns.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trunk Show\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#website\",\"url\":\"https:\/\/www.essensedesigns.com\/de\/\",\"name\":\"Essense Designs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.essensedesigns.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#organization\",\"name\":\"Essense of Australia\",\"url\":\"https:\/\/www.essensedesigns.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/12\/essense_of_australia_logo_svg.svg\",\"contentUrl\":\"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/12\/essense_of_australia_logo_svg.svg\",\"width\":279,\"height\":101,\"caption\":\"Essense of Australia\"},\"image\":{\"@id\":\"https:\/\/www.essensedesigns.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/essenseofaustralia\/\",\"https:\/\/www.instagram.com\/essenseofaustralia\",\"https:\/\/www.pinterest.com\/essensedesigns\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trunk Show - Essense of Australia","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Trunk Show","og_url":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/","og_site_name":"Essense of Australia","article_publisher":"https:\/\/www.facebook.com\/essenseofaustralia\/","og_image":[{"width":1080,"height":1080,"url":"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/09\/social-share-logo-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/","url":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/","name":"Trunk Show - Essense of Australia","isPartOf":{"@id":"https:\/\/www.essensedesigns.com\/de\/#website"},"datePublished":"2026-05-28T16:58:54+00:00","breadcrumb":{"@id":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.essensedesigns.com\/de\/trunk-show\/trunk-show-7590\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.essensedesigns.com\/de\/"},{"@type":"ListItem","position":2,"name":"Trunk Show"}]},{"@type":"WebSite","@id":"https:\/\/www.essensedesigns.com\/de\/#website","url":"https:\/\/www.essensedesigns.com\/de\/","name":"Essense Designs","description":"","publisher":{"@id":"https:\/\/www.essensedesigns.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.essensedesigns.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.essensedesigns.com\/de\/#organization","name":"Essense of Australia","url":"https:\/\/www.essensedesigns.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.essensedesigns.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/12\/essense_of_australia_logo_svg.svg","contentUrl":"https:\/\/cdn.essensedesigns.com\/uploads\/2022\/12\/essense_of_australia_logo_svg.svg","width":279,"height":101,"caption":"Essense of Australia"},"image":{"@id":"https:\/\/www.essensedesigns.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/essenseofaustralia\/","https:\/\/www.instagram.com\/essenseofaustralia","https:\/\/www.pinterest.com\/essensedesigns\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.essensedesigns.com\/de\/wp-json\/wp\/v2\/trunk-show\/123091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.essensedesigns.com\/de\/wp-json\/wp\/v2\/trunk-show"}],"about":[{"href":"https:\/\/www.essensedesigns.com\/de\/wp-json\/wp\/v2\/types\/trunk-show"}],"author":[{"embeddable":true,"href":"https:\/\/www.essensedesigns.com\/de\/wp-json\/wp\/v2\/users\/10"}],"wp:attachment":[{"href":"https:\/\/www.essensedesigns.com\/de\/wp-json\/wp\/v2\/media?parent=123091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}